{"id":40871,"date":"2022-09-20T12:35:21","date_gmt":"2022-09-20T10:35:21","guid":{"rendered":"https:\/\/www.sssh.ch\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/"},"modified":"2024-10-18T16:35:44","modified_gmt":"2024-10-18T14:35:44","slug":"ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt","status":"publish","type":"forum","link":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/","title":{"rendered":"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"forum_cat":[1205],"parution":[],"page_sommaire":[],"class_list":["post-40871","forum","type-forum","status-publish","hentry","forum_cat-forum-1-2018-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT) - sssh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT) - sssh\" \/>\n<meta property=\"og:description\" content=\"Autor: Brigitte Keller\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/\" \/>\n<meta property=\"og:site_name\" content=\"sssh\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T14:35:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sssh.ch\\\/de\\\/forum\\\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\\\/\",\"url\":\"https:\\\/\\\/sssh.ch\\\/de\\\/forum\\\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\\\/\",\"name\":\"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \\\/ Technologinnen (MPT) - sssh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#website\"},\"datePublished\":\"2022-09-20T10:35:21+00:00\",\"dateModified\":\"2024-10-18T14:35:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sssh.ch\\\/de\\\/forum\\\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sssh.ch\\\/de\\\/forum\\\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sssh.ch\\\/de\\\/forum\\\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SSSH\",\"item\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forum\",\"item\":\"https:\\\/\\\/sssh.ch\\\/it\\\/forum\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Forum 1-2018\",\"item\":\"https:\\\/\\\/sssh.ch\\\/de\\\/forum_cat\\\/forum-1-2018-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \\\/ Technologinnen (MPT)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/\",\"name\":\"sssh\",\"description\":\"Soci\u00e9t\u00e9 suisse de st\u00e9rilisation hospitali\u00e8re\",\"publisher\":{\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#organization\",\"name\":\"sssh\",\"url\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sssh.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-cropped-cropped-cropped-cropped-cropped-cropped-SGSV-SSSH_SSSO_Q_NEUTRE_blanc-768x186-1-1-1.png\",\"contentUrl\":\"https:\\\/\\\/sssh.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-cropped-cropped-cropped-cropped-cropped-cropped-SGSV-SSSH_SSSO_Q_NEUTRE_blanc-768x186-1-1-1.png\",\"width\":558,\"height\":186,\"caption\":\"sssh\"},\"image\":{\"@id\":\"https:\\\/\\\/sssh.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT) - sssh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT) - sssh","og_description":"Autor: Brigitte Keller","og_url":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/","og_site_name":"sssh","article_modified_time":"2024-10-18T14:35:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/","url":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/","name":"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT) - sssh","isPartOf":{"@id":"https:\/\/sssh.ch\/fr\/#website"},"datePublished":"2022-09-20T10:35:21+00:00","dateModified":"2024-10-18T14:35:44+00:00","breadcrumb":{"@id":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sssh.ch\/de\/forum\/ueberbetriebliche-kurse-medizinprodukte-technologen-technologinnen-mpt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SSSH","item":"https:\/\/sssh.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Forum","item":"https:\/\/sssh.ch\/it\/forum\/"},{"@type":"ListItem","position":3,"name":"Forum 1-2018","item":"https:\/\/sssh.ch\/de\/forum_cat\/forum-1-2018-2\/"},{"@type":"ListItem","position":4,"name":"\u00dcberbetriebliche Kurse Medizinprodukte Technologen \/ Technologinnen (MPT)"}]},{"@type":"WebSite","@id":"https:\/\/sssh.ch\/fr\/#website","url":"https:\/\/sssh.ch\/fr\/","name":"sssh","description":"Soci\u00e9t\u00e9 suisse de st\u00e9rilisation hospitali\u00e8re","publisher":{"@id":"https:\/\/sssh.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sssh.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sssh.ch\/fr\/#organization","name":"sssh","url":"https:\/\/sssh.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sssh.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/sssh.ch\/wp-content\/uploads\/2021\/09\/cropped-cropped-cropped-cropped-cropped-cropped-cropped-SGSV-SSSH_SSSO_Q_NEUTRE_blanc-768x186-1-1-1.png","contentUrl":"https:\/\/sssh.ch\/wp-content\/uploads\/2021\/09\/cropped-cropped-cropped-cropped-cropped-cropped-cropped-SGSV-SSSH_SSSO_Q_NEUTRE_blanc-768x186-1-1-1.png","width":558,"height":186,"caption":"sssh"},"image":{"@id":"https:\/\/sssh.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/forum\/40871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/forum"}],"about":[{"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/types\/forum"}],"version-history":[{"count":1,"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/forum\/40871\/revisions"}],"predecessor-version":[{"id":45610,"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/forum\/40871\/revisions\/45610"}],"wp:attachment":[{"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/media?parent=40871"}],"wp:term":[{"taxonomy":"forum_cat","embeddable":true,"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/forum_cat?post=40871"},{"taxonomy":"parution","embeddable":true,"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/parution?post=40871"},{"taxonomy":"page_sommaire","embeddable":true,"href":"https:\/\/sssh.ch\/de\/wp-json\/wp\/v2\/page_sommaire?post=40871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}